{"id":7189,"date":"2025-12-25T08:50:40","date_gmt":"2025-12-25T08:50:40","guid":{"rendered":"https:\/\/composite-box.com\/?p=7189"},"modified":"2026-03-13T09:44:50","modified_gmt":"2026-03-13T09:44:50","slug":"soluciones-ligeras-para-puertas-traseras-y-laterales-de-camiones-frigorificos","status":"publish","type":"post","link":"https:\/\/composite-box.com\/es\/blog\/lightweight-solutions-for-refrigerated-truck-rear-and-side-doors\/","title":{"rendered":"Soluciones ligeras para puertas traseras y laterales de camiones frigor\u00edficos"},"content":{"rendered":"<h2 class=\"wp-block-heading\">La importancia de las puertas traseras y laterales ligeras<\/h2>\n\n\n\n<p>En los dise\u00f1os tradicionales de veh\u00edculos frigor\u00edficos se suele emplear una construcci\u00f3n totalmente de acero, lo que da lugar a estructuras excepcionalmente pesadas. S\u00f3lo una puerta trasera de tama\u00f1o est\u00e1ndar puede llegar a pesar <strong>150 kilos<\/strong>, y, cuando se combina con el peso de las puertas laterales, el peso total puede superar los 200 kilogramos. Esto no solo reduce directamente la capacidad de carga \u00fatil del veh\u00edculo, sino que tambi\u00e9n aumenta el consumo de combustible, lo que eleva considerablemente los costes operativos.<\/p>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-7189_630cfe-44{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-7189_630cfe-44 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-7189_630cfe-44 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-7189_630cfe-44 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-7189_630cfe-44 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-7189_630cfe-44 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"2\" data-columns-xl=\"2\" data-columns-md=\"2\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-3.jpg\" width=\"750\" height=\"500\" alt=\"\" data-full-image=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-3.jpg\" data-light-image=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-3.jpg\" data-id=\"6497\" class=\"wp-image-6497\" srcset=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-3.jpg 750w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-3-300x200.jpg 300w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-3-18x12.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-4.jpg\" width=\"750\" height=\"500\" alt=\"\" data-full-image=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-4.jpg\" data-light-image=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-4.jpg\" data-id=\"6496\" class=\"wp-image-6496\" srcset=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-4.jpg 750w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-4-300x200.jpg 300w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-4-18x12.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-2.jpg\" width=\"750\" height=\"500\" alt=\"\" data-full-image=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-2.jpg\" data-light-image=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-2.jpg\" data-id=\"6495\" class=\"wp-image-6495\" srcset=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-2.jpg 750w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-2-300x200.jpg 300w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-2-18x12.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body.jpg\" width=\"750\" height=\"500\" alt=\"\" data-full-image=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body.jpg\" data-light-image=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body.jpg\" data-id=\"6494\" class=\"wp-image-6494\" srcset=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body.jpg 750w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-300x200.jpg 300w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/09\/Rear-3-Door-Composite-Truck-Body-18x12.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<h2 class=\"wp-block-heading\">Composite Box desarrolla soluciones de aligeramiento eficaces<\/h2>\n\n\n\n<p>A trav\u00e9s de a\u00f1os de investigaci\u00f3n, Composite Box ha descubierto que reducir el peso de las puertas de camiones frigor\u00edficos no es simplemente una cuesti\u00f3n de sustituci\u00f3n de materiales. Nuestro objetivo va m\u00e1s all\u00e1 de la mera reducci\u00f3n del peso propio; tambi\u00e9n garantizamos y mejoramos caracter\u00edsticas de rendimiento cr\u00edticas como el aislamiento t\u00e9rmico, la integridad del sellado y la resistencia a los impactos. Garantizamos que, aunque se reduzca el peso, el rendimiento en todos los aspectos permanece inalterado.<\/p>\n\n\n\n<p><strong>Para lograr este objetivo, Composite Box ha establecido tres principios b\u00e1sicos:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Optimizaci\u00f3n estructural<\/li>\n\n\n\n<li>Innovaci\u00f3n de materiales<\/li>\n\n\n\n<li>Avance del proceso.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Soluci\u00f3n ligera detallada:<\/h2>\n\n\n\n<p>El Composite Box emplea una soluci\u00f3n ligera de material compuesto de eficacia probada: una estructura compuesta por una piel de FRP, un n\u00facleo de espuma aislante y un refuerzo interno de acero. Cada una de estas tres capas ofrece caracter\u00edsticas distintas:<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong><a href=\"https:\/\/composite-box.com\/es\/planchas-de-frp-plastico-reforzado-con-fibra-de-vidrio\/\">Piel de pl\u00e1stico reforzado con fibra (FRP)<\/a>: <\/strong>Sustituye a los paneles de acero tradicionales con una resistencia superior a los impactos y a los ara\u00f1azos.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><style>.kb-image7189_ca7d9f-32 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image7189_ca7d9f-32 size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"214\" src=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/04\/glasteel-frp-panels-300x214.jpg\" alt=\"frp-panels\" class=\"kb-img wp-image-4761\" srcset=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/04\/glasteel-frp-panels-300x214.jpg 300w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/04\/glasteel-frp-panels.jpg 308w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>N\u00facleo aislante de alta eficiencia:<\/strong> Relleno de poliuretano o <a href=\"https:\/\/composite-box.com\/es\/placa-aislante-de-espuma-xps\/\">Espuma r\u00edgida XPS<\/a>. Estos materiales poseen una conductividad t\u00e9rmica extremadamente baja, por lo que act\u00faan como aislantes muy eficaces que reducen significativamente el valor U global de la puerta.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><style>.kb-image7189_23b5f0-8e .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image7189_23b5f0-8e size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/12\/Lightweight-Solution-for-Refrigerated-Truck-Rear-Doors-300x200.jpg\" alt=\"\" class=\"kb-img wp-image-7191\" srcset=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/12\/Lightweight-Solution-for-Refrigerated-Truck-Rear-Doors-300x200.jpg 300w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/12\/Lightweight-Solution-for-Refrigerated-Truck-Rear-Doors-1024x683.jpg 1024w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/12\/Lightweight-Solution-for-Refrigerated-Truck-Rear-Doors-768x512.jpg 768w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/12\/Lightweight-Solution-for-Refrigerated-Truck-Rear-Doors-18x12.jpg 18w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/12\/Lightweight-Solution-for-Refrigerated-Truck-Rear-Doors.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>Bastidor de alta resistencia:<\/strong> Un esqueleto de acero reforzado integrado proporciona soporte estructural al n\u00facleo, garantizando una resistencia fiable a los impactos y durabilidad incluso en condiciones de funcionamiento frecuente y carga de peso propio.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><style>.kb-image7189_9e6c3c-06 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image7189_9e6c3c-06 size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/02\/side-door-frame-2-300x200.jpg\" alt=\"Marco de la puerta lateral de la carrocer\u00eda del cami\u00f3n de acero inoxidable -2\" class=\"kb-img wp-image-3703\" srcset=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/02\/side-door-frame-2-300x200.jpg 300w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/02\/side-door-frame-2-600x400.jpg 600w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/02\/side-door-frame-2.jpg 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 componentes se utilizan en la puerta trasera ligera?<\/h2>\n\n\n\n<p>Para los componentes, nos ce\u00f1imos a los principios de ligereza y durabilidad, seleccionando dise\u00f1os y materiales l\u00edderes del sector.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sistema de elevaci\u00f3n<\/strong><\/h3>\n\n\n\n<p>Tradicionalmente utiliz\u00e1bamos sistemas de elevaci\u00f3n de hierro fundido, pero ahora empleamos barras de bloqueo de aleaci\u00f3n de aluminio de alta resistencia, lo que reduce significativamente el peso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><a href=\"https:\/\/composite-box.com\/es\/cerraduras-y-bisagras-para-camiones\/\">Sistema de bisagras<\/a><\/strong><\/h3>\n\n\n\n<p>Incorpora tornillos\/remaches ligeros y calzos que reducen el peso. Los casquillos de material compuesto sustituyen parcialmente a los cojinetes met\u00e1licos.<\/p>\n\n\n<style>.kb-image7189_d822c9-ad .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image7189_d822c9-ad size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/04\/hinges-300x200.jpg\" alt=\"\" class=\"kb-img wp-image-5143\" srcset=\"https:\/\/composite-box.com\/wp-content\/uploads\/2025\/04\/hinges-300x200.jpg 300w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/04\/hinges-18x12.jpg 18w, https:\/\/composite-box.com\/wp-content\/uploads\/2025\/04\/hinges.jpg 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Componentes de sellado<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tira de sellado: <\/strong>Utiliza material TPE duradero, resistente al envejecimiento y el\u00e1stico para una menor densidad y una flexibilidad superior.<\/li>\n\n\n\n<li><strong>Cinta de sellado magn\u00e9tico:<\/strong> Incorpora bandas magn\u00e9ticas flexibles que ayudan magn\u00e9ticamente a la adhesi\u00f3n al marco de la puerta, mejorando la eficacia del sellado y reduciendo la resistencia al cierre.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Componentes ligeros<\/strong><\/h3>\n\n\n\n<p>Los paneles del revestimiento interior, las barras del parachoques y los sistemas de iluminaci\u00f3n adoptan los \u00faltimos principios de dise\u00f1o, dando prioridad a la construcci\u00f3n ligera y la durabilidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ventajas de utilizar puertas traseras ligeras<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Mayor eficiencia econ\u00f3mica:<\/h3>\n\n\n\n<p>Las carrocer\u00edas de puertas ligeras reducen el peso en 50%, lo que aumenta la capacidad de carga e incrementa los ingresos. La reducci\u00f3n de peso tambi\u00e9n disminuye el consumo de combustible.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mayor eficiencia operativa:<\/h3>\n\n\n\n<p>Las puertas laterales y traseras ligeras facilitan una apertura\/cierre m\u00e1s suave, ahorrando tiempo. Con m\u00e1s de 20 ciclos diarios, se ahorra media hora, aumentando el tiempo operativo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rendimiento de aislamiento mejorado:<\/h3>\n\n\n\n<p>El aislamiento interno de espuma de poliuretano bloquea eficazmente las fugas de aire fr\u00edo, reduciendo el consumo de energ\u00eda de la unidad de refrigeraci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>La importancia de las puertas traseras y laterales ligeras En los dise\u00f1os tradicionales de veh\u00edculos frigor\u00edficos,...<\/p>","protected":false},"author":1,"featured_media":7191,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1],"tags":[85],"class_list":["post-7189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-door"],"taxonomy_info":{"category":[{"value":1,"label":"Uncategorized"}],"post_tag":[{"value":85,"label":"door"}]},"featured_image_src_large":["https:\/\/composite-box.com\/wp-content\/uploads\/2025\/12\/Lightweight-Solution-for-Refrigerated-Truck-Rear-Doors-1024x683.jpg",1024,683,true],"author_info":{"display_name":"yuzijie-topolo","author_link":"https:\/\/composite-box.com\/es\/author\/yuzijie-topolo\/"},"comment_info":0,"category_info":[{"term_id":1,"name":"Uncategorized","slug":"uncategorized","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":13,"filter":"raw","term_order":"0","cat_ID":1,"category_count":13,"category_description":"","cat_name":"Uncategorized","category_nicename":"uncategorized","category_parent":0}],"tag_info":[{"term_id":85,"name":"door","slug":"door","term_group":0,"term_taxonomy_id":85,"taxonomy":"post_tag","description":"","parent":0,"count":4,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/composite-box.com\/es\/wp-json\/wp\/v2\/posts\/7189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/composite-box.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/composite-box.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/composite-box.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/composite-box.com\/es\/wp-json\/wp\/v2\/comments?post=7189"}],"version-history":[{"count":5,"href":"https:\/\/composite-box.com\/es\/wp-json\/wp\/v2\/posts\/7189\/revisions"}],"predecessor-version":[{"id":7202,"href":"https:\/\/composite-box.com\/es\/wp-json\/wp\/v2\/posts\/7189\/revisions\/7202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/composite-box.com\/es\/wp-json\/wp\/v2\/media\/7191"}],"wp:attachment":[{"href":"https:\/\/composite-box.com\/es\/wp-json\/wp\/v2\/media?parent=7189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/composite-box.com\/es\/wp-json\/wp\/v2\/categories?post=7189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/composite-box.com\/es\/wp-json\/wp\/v2\/tags?post=7189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}